{"id":3246,"date":"2018-02-13T14:54:24","date_gmt":"2018-02-13T13:54:24","guid":{"rendered":"http:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935.jpg"},"modified":"2018-02-13T14:54:24","modified_gmt":"2018-02-13T13:54:24","slug":"20171229_122935","status":"inherit","type":"attachment","link":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/20171229_122935\/","title":{"rendered":"20171229_122935"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3246","attachment","type-attachment","status-inherit","czr-hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a class=\"grouped_elements\" rel=\"tc-fancybox-group\" href=\"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-scaled.jpg\" title=\"20171229_122935\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-300x225.jpg 300w, https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-600x450.jpg 600w, https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-768x576.jpg 768w, https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"2018\/02\/20171229_122935-scaled.jpg","sizes":{"woocommerce_thumbnail":{"file":"20171229_122935-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"20171229_122935-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-100x100.jpg"},"woocommerce_single":{"file":"20171229_122935-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-600x450.jpg"},"thumbnail":{"file":"20171229_122935-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-150x150.jpg"},"medium":{"file":"20171229_122935-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-300x225.jpg"},"medium_large":{"file":"20171229_122935-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-768x576.jpg"},"large":{"file":"20171229_122935-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-1024x768.jpg"},"tc_rectangular_size":{"file":"20171229_122935-1170x250.jpg","width":1170,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-1170x250.jpg"},"tc-grid-full":{"file":"20171229_122935-1170x350.jpg","width":1170,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-1170x350.jpg"},"tc-grid":{"file":"20171229_122935-570x350.jpg","width":570,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-570x350.jpg"},"tc-thumb":{"file":"20171229_122935-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-270x250.jpg"},"slider-full":{"file":"20171229_122935-4032x400.jpg","width":4032,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-4032x400.jpg"},"slider":{"file":"20171229_122935-1170x400.jpg","width":1170,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-1170x400.jpg"},"fpc-size":{"file":"20171229_122935-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-270x250.jpg"},"full":{"file":"20171229_122935-scaled.jpg","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-scaled.jpg"}},"image_meta":{"aperture":"1.7","credit":"","camera":"SM-G955F","caption":"","created_timestamp":"1514550575","copyright":"","focal_length":"4.2","iso":"40","shutter_speed":"0.006993006993007","title":"","orientation":"1","keywords":[]},"original_image":"20171229_122935.jpg"},"post":null,"source_url":"https:\/\/oledinteractive.lu\/wp\/wp-content\/uploads\/2018\/02\/20171229_122935-scaled.jpg","filename":"20171229_122935.jpg","filesize":4576636,"_links":{"self":[{"href":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/wp-json\/wp\/v2\/media\/3246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oledinteractive.lu\/ecran-geant-led-luxembourg-belgique\/wp-json\/wp\/v2\/comments?post=3246"}]}}